{"id":772,"count":7,"description":"","link":"https:\/\/www.santosgrills.de\/grill-magazin\/tag\/wagyu\/","name":"Wagy\u016b","slug":"wagyu","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Wagy\u016b Archive - SANTOS Grill Magazin<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wagy\u016b Archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.santosgrills.de\/grill-magazin\/tag\/wagyu\/\" \/>\n<meta property=\"og:site_name\" content=\"SANTOS Grill Magazin\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.santosgrills.de\/grill-magazin\/wp-content\/uploads\/2021\/08\/logo-santos-social.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1050\" \/>\n\t<meta property=\"og:image:height\" content=\"588\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@santosgrillsde\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/tag\\\/wagyu\\\/\",\"url\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/tag\\\/wagyu\\\/\",\"name\":\"Wagy\u016b Archive - SANTOS Grill Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/tag\\\/wagyu\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/tag\\\/wagyu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wagy\u016b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/\",\"name\":\"SANTOS Grill Magazin\",\"description\":\"Grill- und BBQ-Magazin, Grillrezepte, Tipps &amp; Tricks.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/#organization\",\"name\":\"SANTOS Grill Shop\",\"url\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/45494989_2039087046134150_3012855421397368832_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/45494989_2039087046134150_3012855421397368832_n.jpg\",\"width\":1682,\"height\":1682,\"caption\":\"SANTOS Grill Shop\"},\"image\":{\"@id\":\"https:\\\/\\\/www.santosgrills.de\\\/grill-magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/santosgrills.de\\\/\",\"https:\\\/\\\/x.com\\\/santosgrillsde\",\"https:\\\/\\\/www.instagram.com\\\/santosgrills\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/santosgrills\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/santosgrill\",\"https:\\\/\\\/www.tiktok.com\\\/@santosgrills\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wagy\u016b Archive - SANTOS Grill Magazin","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Wagy\u016b Archive","og_url":"https:\/\/www.santosgrills.de\/grill-magazin\/tag\/wagyu\/","og_site_name":"SANTOS Grill Magazin","og_image":[{"width":1050,"height":588,"url":"https:\/\/www.santosgrills.de\/grill-magazin\/wp-content\/uploads\/2021\/08\/logo-santos-social.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@santosgrillsde","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.santosgrills.de\/grill-magazin\/tag\/wagyu\/","url":"https:\/\/www.santosgrills.de\/grill-magazin\/tag\/wagyu\/","name":"Wagy\u016b Archive - SANTOS Grill Magazin","isPartOf":{"@id":"https:\/\/www.santosgrills.de\/grill-magazin\/#website"},"breadcrumb":{"@id":"https:\/\/www.santosgrills.de\/grill-magazin\/tag\/wagyu\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.santosgrills.de\/grill-magazin\/tag\/wagyu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.santosgrills.de\/grill-magazin\/"},{"@type":"ListItem","position":2,"name":"Wagy\u016b"}]},{"@type":"WebSite","@id":"https:\/\/www.santosgrills.de\/grill-magazin\/#website","url":"https:\/\/www.santosgrills.de\/grill-magazin\/","name":"SANTOS Grill Magazin","description":"Grill- und BBQ-Magazin, Grillrezepte, Tipps &amp; Tricks.","publisher":{"@id":"https:\/\/www.santosgrills.de\/grill-magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.santosgrills.de\/grill-magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.santosgrills.de\/grill-magazin\/#organization","name":"SANTOS Grill Shop","url":"https:\/\/www.santosgrills.de\/grill-magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.santosgrills.de\/grill-magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.santosgrills.de\/grill-magazin\/wp-content\/uploads\/2021\/08\/45494989_2039087046134150_3012855421397368832_n.jpg","contentUrl":"https:\/\/www.santosgrills.de\/grill-magazin\/wp-content\/uploads\/2021\/08\/45494989_2039087046134150_3012855421397368832_n.jpg","width":1682,"height":1682,"caption":"SANTOS Grill Shop"},"image":{"@id":"https:\/\/www.santosgrills.de\/grill-magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/santosgrills.de\/","https:\/\/x.com\/santosgrillsde","https:\/\/www.instagram.com\/santosgrills\/","https:\/\/www.linkedin.com\/company\/santosgrills","https:\/\/www.youtube.com\/c\/santosgrill","https:\/\/www.tiktok.com\/@santosgrills"]}]}},"_links":{"self":[{"href":"https:\/\/www.santosgrills.de\/grill-magazin\/wp-json\/wp\/v2\/tags\/772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santosgrills.de\/grill-magazin\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.santosgrills.de\/grill-magazin\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.santosgrills.de\/grill-magazin\/wp-json\/wp\/v2\/posts?tags=772"},{"href":"https:\/\/www.santosgrills.de\/grill-magazin\/wp-json\/wp\/v2\/grillrezepte?tags=772"},{"href":"https:\/\/www.santosgrills.de\/grill-magazin\/wp-json\/wp\/v2\/fragen_und_antworten?tags=772"},{"href":"https:\/\/www.santosgrills.de\/grill-magazin\/wp-json\/wp\/v2\/grillnews?tags=772"},{"href":"https:\/\/www.santosgrills.de\/grill-magazin\/wp-json\/wp\/v2\/grilltests?tags=772"},{"href":"https:\/\/www.santosgrills.de\/grill-magazin\/wp-json\/wp\/v2\/tipps_und_tricks?tags=772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}